{"id":24344,"date":"2025-01-31T08:32:30","date_gmt":"2025-01-31T07:32:30","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=24344"},"modified":"2026-07-08T15:18:11","modified_gmt":"2026-07-08T13:18:11","slug":"divain-181","status":"publish","type":"product","link":"https:\/\/divainers.com\/de\/producto\/divain-181\/","title":{"rendered":"divain.181"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Suchst du ein Parfum, das die Essenz von <i>Amarige<\/i> von Givenchy einf\u00e4ngt? <b>DIVAIN-181<\/b> ist genau das, was du brauchst. Eine orientalisch florale Komposition f\u00fcr Damen \u2014 entworfen, um dir diesen ikonischen Vibe zum Bruchteil des Preises zu geben.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Es \u00f6ffnet sich mit <b>flor orangenbl\u00fcte naranjo, pflaume, mandarine, veilchen, pfirsich, neroli, palo rose brasil<\/b> \u2014 frisch und einladend. Dann entwickelt es sich zu einem Herzen aus <b>bayas rojas, mimosa, clavel, acacia negra, nardos, ar\u00e1ndanos, gardenia, casia, orqu\u00eddea, jasmin, ylang-ylang, rose<\/b>, der Teil, der das Parfum wirklich zum Singen bringt. Und es endet auf einer Basis aus <b>sandelholz, tonkabohne, amber, moschus, vanille, holzige noten, zeder<\/b> f\u00fcr diesen anhaltenden Eindruck.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ehrlich gesagt, es ist ein intensives Parfum \u2014 ideal im Herbst, f\u00fcr den Abend. Die Art Duft, die zu deiner Signatur wird.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Wenn du Amarige liebst, aber nicht das ganze Geld f\u00fcr Givenchy ausgeben willst, gibt dir <b>DIVAIN-181<\/b> den gleichen Charakter, ohne dein Sparschwein zu zerbrechen. Hochwertiger Duft sollte nicht unerreichbar sein \u2014 genau das machen wir hier. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Erinnert an Amarige von Givenchy<\/p>\n","protected":false},"featured_media":52165,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5038],"product_tag":[4800],"class_list":["post-24344","product","type-product","status-publish","has-post-thumbnail","product_cat-givenchy","product_tag-damen","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product\/24344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/comments?post=24344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/media\/52165"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/media?parent=24344"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_brand?post=24344"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_cat?post=24344"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_tag?post=24344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}