{"id":24480,"date":"2025-01-31T08:33:20","date_gmt":"2025-01-31T07:33:20","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=24480"},"modified":"2026-07-08T13:08:31","modified_gmt":"2026-07-08T11:08:31","slug":"divain-326","status":"publish","type":"product","link":"https:\/\/divainers.com\/de\/producto\/divain-326\/","title":{"rendered":"divain.326"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Suchst du ein Parfum, das die Essenz von <i>Agarbathi<\/i> von Penhaligon\u2019s einf\u00e4ngt? <b>DIVAIN-326<\/b> ist genau das, was du brauchst. Eine foug\u00e8re orientalische Komposition f\u00fcr Herren \u2014 entworfen, um dir diesen ikonischen Vibe zum Bruchteil des Preises zu geben.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Es \u00f6ffnet sich mit <b>palo santo, bergamotte, rosa pfeffer<\/b> \u2014 frisch und einladend. Dann entwickelt es sich zu einem Herzen aus <b>weihrauch, weihrauch ol\u00edbano, leche, sambac-jasmin<\/b>, der Teil, der das Parfum wirklich zum Singen bringt. Und es endet auf einer Basis aus <b>gamuza, abeto bals\u00e1mico, sandelholz, vetiver<\/b> f\u00fcr diesen anhaltenden Eindruck.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ehrlich gesagt, es ist ein ausgewogenes Parfum \u2014 ideal im Winter, f\u00fcr den Abend. Die Art Duft, die zu deiner Signatur wird.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Wenn du Agarbathi liebst, aber nicht das ganze Geld f\u00fcr Penhaligon\u2019s ausgeben willst, gibt dir <b>DIVAIN-326<\/b> den gleichen Charakter, ohne dein Sparschwein zu zerbrechen. Hochwertiger Duft sollte nicht unerreichbar sein \u2014 genau das machen wir hier. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Erinnert an Agarbathi von Penhaligon\u2019s<\/p>\n","protected":false},"featured_media":51061,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5095],"product_tag":[4801],"class_list":["post-24480","product","type-product","status-publish","has-post-thumbnail","product_cat-penhaligons","product_tag-herren","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product\/24480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/comments?post=24480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/media\/51061"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/media?parent=24480"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_brand?post=24480"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_cat?post=24480"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_tag?post=24480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}