{"id":24736,"date":"2025-01-31T08:32:51","date_gmt":"2025-01-31T07:32:51","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=24736"},"modified":"2026-07-08T09:10:56","modified_gmt":"2026-07-08T07:10:56","slug":"divain-601","status":"publish","type":"product","link":"https:\/\/divainers.com\/de\/producto\/divain-601\/","title":{"rendered":"divain.601"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Suchst du ein Parfum, das die Essenz von <i>Id\u00f4le<\/i> von Lanc\u00f4me einf\u00e4ngt? <b>DIVAIN-601<\/b> ist genau das, was du brauchst. Eine moschus florale Komposition f\u00fcr Damen \u2014 entworfen, um dir diesen ikonischen Vibe zum Bruchteil des Preises zu geben.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Es \u00f6ffnet sich mit <b>bergamotte, birne<\/b> \u2014 frisch und einladend. Dann entwickelt es sich zu einem Herzen aus <b>rose turca, rose mai, jasmin india<\/b>, der Teil, der das Parfum wirklich zum Singen bringt. Und es endet auf einer Basis aus <b>moschus blanco, vanille<\/b> f\u00fcr diesen anhaltenden Eindruck.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ehrlich gesagt, es ist ein ausgewogenes Parfum \u2014 ideal im Fr\u00fchling, f\u00fcr den Tag. Die Art Duft, die zu deiner Signatur wird.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Wenn du Id\u00f4le liebst, aber nicht das ganze Geld f\u00fcr Lanc\u00f4me ausgeben willst, gibt dir <b>DIVAIN-601<\/b> den gleichen Charakter, ohne dein Sparschwein zu zerbrechen. Hochwertiger Duft sollte nicht unerreichbar sein \u2014 genau das machen wir hier. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Erinnert an Id\u00f4le von Lanc\u00f4me<\/p>\n","protected":false},"featured_media":49063,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5062],"product_tag":[4800],"class_list":["post-24736","product","type-product","status-publish","has-post-thumbnail","product_cat-lancome","product_tag-damen","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product\/24736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/comments?post=24736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/media\/49063"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/media?parent=24736"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_brand?post=24736"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_cat?post=24736"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_tag?post=24736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}