{"id":24848,"date":"2025-01-31T08:32:35","date_gmt":"2025-01-31T07:32:35","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=24848"},"modified":"2026-07-07T15:37:05","modified_gmt":"2026-07-07T13:37:05","slug":"divain-723","status":"publish","type":"product","link":"https:\/\/divainers.com\/de\/producto\/divain-723\/","title":{"rendered":"divain.723"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Suchst du ein Parfum, das die Essenz von <i>La Petite Robe Noire Nectar<\/i> von Guerlain einf\u00e4ngt? <b>DIVAIN-723<\/b> ist genau das, was du brauchst. Eine floral orientalische Komposition f\u00fcr Damen \u2014 entworfen, um dir diesen ikonischen Vibe zum Bruchteil des Preises zu geben.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Es \u00f6ffnet sich mit <b>mandel, macaron, bergamotte<\/b> \u2014 frisch und einladend. Dann entwickelt es sich zu einem Herzen aus <b>honig, rose bulgaria, rose turca<\/b>, der Teil, der das Parfum wirklich zum Singen bringt. Und es endet auf einer Basis aus <b>tonkabohne, patchouli<\/b> f\u00fcr diesen anhaltenden Eindruck.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ehrlich gesagt, es ist ein ausgewogenes Parfum \u2014 ideal im Fr\u00fchling, f\u00fcr den Tag. Die Art Duft, die zu deiner Signatur wird.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Wenn du La Petite Robe Noire Nectar liebst, aber nicht das ganze Geld f\u00fcr Guerlain ausgeben willst, gibt dir <b>DIVAIN-723<\/b> den gleichen Charakter, ohne dein Sparschwein zu zerbrechen. Hochwertiger Duft sollte nicht unerreichbar sein \u2014 genau das machen wir hier. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Erinnert an La Petite Robe Noire Nectar von Guerlain<\/p>\n","protected":false},"featured_media":48108,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5042],"product_tag":[4800],"class_list":["post-24848","product","type-product","status-publish","has-post-thumbnail","product_cat-guerlain","product_tag-damen","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product\/24848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/comments?post=24848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/media\/48108"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/media?parent=24848"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_brand?post=24848"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_cat?post=24848"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_tag?post=24848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}