{"id":25138,"date":"2025-07-07T11:23:45","date_gmt":"2025-07-07T09:23:45","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=25138"},"modified":"2026-06-24T14:09:07","modified_gmt":"2026-06-24T12:09:07","slug":"divain-1048","status":"publish","type":"product","link":"https:\/\/divainers.com\/de\/producto\/divain-1048\/","title":{"rendered":"divain.1048"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Suchst du ein Parfum, das die Essenz von <i>Forbidden Games<\/i> von By Kilian einf\u00e4ngt? <b>DIVAIN-1048<\/b> ist genau das, was du brauchst. Eine floral orientalische Komposition f\u00fcr Damen \u2014 entworfen, um dir diesen ikonischen Vibe zum Bruchteil des Preises zu geben.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Es \u00f6ffnet sich mit <b>pfirsich, apfel, pflaume, zimt<\/b> \u2014 frisch und einladend. Dann entwickelt es sich zu einem Herzen aus <b>rose damascena bulgaria, jasmin, geranie bourbon<\/b>, der Teil, der das Parfum wirklich zum Singen bringt. Und es endet auf einer Basis aus <b>honig, vanille, opop\u00f3naco<\/b> f\u00fcr diesen anhaltenden Eindruck.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ehrlich gesagt, es ist ein ausgewogenes Parfum \u2014 ideal im Fr\u00fchling, f\u00fcr den Tag. Die Art Duft, die zu deiner Signatur wird.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Wenn du Forbidden Games liebst, aber nicht das ganze Geld f\u00fcr By Kilian ausgeben willst, gibt dir <b>DIVAIN-1048<\/b> den gleichen Charakter, ohne dein Sparschwein zu zerbrechen. Hochwertiger Duft sollte nicht unerreichbar sein \u2014 genau das machen wir hier. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Erinnert an Forbidden Games von By Kilian<\/p>\n","protected":false},"featured_media":8599,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5002],"product_tag":[4800],"class_list":["post-25138","product","type-product","status-publish","has-post-thumbnail","product_cat-by-kilian","product_tag-damen","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product\/25138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/comments?post=25138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/media\/8599"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/media?parent=25138"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_brand?post=25138"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_cat?post=25138"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_tag?post=25138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}