{"id":25202,"date":"2026-01-21T13:24:21","date_gmt":"2026-01-21T12:24:21","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=25202"},"modified":"2026-06-24T13:11:43","modified_gmt":"2026-06-24T11:11:43","slug":"divain-1308","status":"publish","type":"product","link":"https:\/\/divainers.com\/de\/producto\/divain-1308\/","title":{"rendered":"divain.1308"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Suchst du ein Parfum, das die Essenz von <i>Perseus<\/i> von Parfums de Marly einf\u00e4ngt? <b>DIVAIN-1308<\/b> ist genau das, was du brauchst. Eine orientalisch holzige Komposition f\u00fcr Herren \u2014 entworfen, um dir diesen ikonischen Vibe zum Bruchteil des Preises zu geben.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Es \u00f6ffnet sich mit <b>grapefruit, bergamotte, ar\u00e1ndanos<\/b> \u2014 frisch und einladend. Dann entwickelt es sich zu einem Herzen aus <b>vetiver, mandarine verde, geranie<\/b>, der Teil, der das Parfum wirklich zum Singen bringt. Und es endet auf einer Basis aus <b>madera seca, madera cachemira, amber gris, abeto bals\u00e1mico, zeder, tonkabohne<\/b> f\u00fcr diesen anhaltenden Eindruck.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ehrlich gesagt, es ist ein intensives Parfum \u2014 ideal im Fr\u00fchling, f\u00fcr den Tag. Die Art Duft, die zu deiner Signatur wird.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Wenn du Perseus liebst, aber nicht das ganze Geld f\u00fcr Parfums de Marly ausgeben willst, gibt dir <b>DIVAIN-1308<\/b> den gleichen Charakter, ohne dein Sparschwein zu zerbrechen. Hochwertiger Duft sollte nicht unerreichbar sein \u2014 genau das machen wir hier. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Erinnert an Perseus von Parfums de Marly<\/p>\n","protected":false},"featured_media":45490,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5093],"product_tag":[4801],"class_list":["post-25202","product","type-product","status-publish","has-post-thumbnail","product_cat-parfums-de-marly","product_tag-herren","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product\/25202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/comments?post=25202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/media\/45490"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/media?parent=25202"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_brand?post=25202"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_cat?post=25202"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/de\/wp-json\/wp\/v2\/product_tag?post=25202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}