{"id":23240,"date":"2025-01-31T08:33:05","date_gmt":"2025-01-31T07:33:05","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=23240"},"modified":"2026-07-08T12:31:49","modified_gmt":"2026-07-08T10:31:49","slug":"divain-371","status":"publish","type":"product","link":"https:\/\/divainers.com\/fr\/producto\/divain-371\/","title":{"rendered":"divain.371"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Tu cherches un parfum qui capture l&rsquo;essence de <i>Legend Red<\/i> par Montblanc ? <b>DIVAIN-371<\/b> est exactement ce qu&rsquo;il te faut. Une composition bois\u00e9 hesp\u00e9rid\u00e9 pour hommes \u2014 con\u00e7ue pour te donner ce vibe iconique \u00e0 une fraction du prix.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Il s&rsquo;ouvre sur <b>orange sanguine, toronja pamplemousse, cardamome<\/b> \u2014 frais et invitant. Puis il \u00e9volue vers un c\u0153ur de <b>c\u00e8dre, bayas enebro, esclarea<\/b>, la partie qui fait vraiment chanter le parfum. Et il s&rsquo;ach\u00e8ve sur un fond de <b>caoba, c\u00e8dre de l&rsquo;Atlas, f\u00e8ve tonka<\/b> pour cette impression durable.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Honn\u00eatement, c&rsquo;est un parfum portable \u2014 id\u00e9al en \u00e9t\u00e9, pour la journ\u00e9e. Le genre de fragrance qui devient ta signature.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si tu aimes Legend Red mais que tu veux pas casser ta tirelire pour Montblanc, <b>DIVAIN-371<\/b> te donne ce m\u00eame caract\u00e8re sans te ruiner. Un parfum de qualit\u00e9 ne devrait pas \u00eatre inaccessible \u2014 c&rsquo;est exactement ce qu&rsquo;on fait ici. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Inspir\u00e9 de Legend Red par Montblanc<\/p>\n","protected":false},"featured_media":43059,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[4910],"product_tag":[4796],"class_list":["post-23240","product","type-product","status-publish","has-post-thumbnail","product_cat-montblanc","product_tag-homme","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/product\/23240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/comments?post=23240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/media\/43059"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/media?parent=23240"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/product_brand?post=23240"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/product_cat?post=23240"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/product_tag?post=23240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}