{"id":23337,"date":"2025-01-31T08:32:45","date_gmt":"2025-01-31T07:32:45","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=23337"},"modified":"2026-07-08T11:17:52","modified_gmt":"2026-07-08T09:17:52","slug":"divain-453","status":"publish","type":"product","link":"https:\/\/divainers.com\/fr\/producto\/divain-453\/","title":{"rendered":"divain.453"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Tu cherches un parfum qui capture l&rsquo;essence de <i>Oudgasm Tobacco Oud | 04<\/i> par Kayal ? <b>DIVAIN-453<\/b> est exactement ce qu&rsquo;il te faut. Une composition oriental bois\u00e9 pour tous \u2014 con\u00e7ue pour te donner ce vibe iconique \u00e0 une fraction du prix.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Il s&rsquo;ouvre sur <b>miel blanca, mandarine, esclarea, g\u00e9ranium, prune<\/b> \u2014 frais et invitant. Puis il \u00e9volue vers un c\u0153ur de <b>safran, clou de girofle olor<\/b>, la partie qui fait vraiment chanter le parfum. Et il s&rsquo;ach\u00e8ve sur un fond de <b>tabac, oud, vanille, pralin\u00e9, benjoin, pachul\u00ed<\/b> pour cette impression durable.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Honn\u00eatement, c&rsquo;est un parfum \u00e9quilibr\u00e9, portable \u2014 id\u00e9al en hiver, pour la soir\u00e9e. Le genre de fragrance qui devient ta signature.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si tu aimes Oudgasm Tobacco Oud | 04 mais que tu veux pas casser ta tirelire pour Kayal, <b>DIVAIN-453<\/b> te donne ce m\u00eame caract\u00e8re sans te ruiner. Un parfum de qualit\u00e9 ne devrait pas \u00eatre inaccessible \u2014 c&rsquo;est exactement ce qu&rsquo;on fait ici. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Inspir\u00e9 de Oudgasm Tobacco Oud | 04 par Kayal<\/p>\n","protected":false},"featured_media":42498,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[4887],"product_tag":[4798],"class_list":["post-23337","product","type-product","status-publish","has-post-thumbnail","product_cat-kayali","product_tag-unisex","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/product\/23337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/comments?post=23337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/media\/42498"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/media?parent=23337"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/product_brand?post=23337"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/product_cat?post=23337"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/fr\/wp-json\/wp\/v2\/product_tag?post=23337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}