{"id":25684,"date":"2025-01-31T08:32:38","date_gmt":"2025-01-31T07:32:38","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=25684"},"modified":"2026-07-08T13:17:59","modified_gmt":"2026-07-08T11:17:59","slug":"divain-316","status":"publish","type":"product","link":"https:\/\/divainers.com\/it\/producto\/divain-316\/","title":{"rendered":"divain.316"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Cerchi un profumo che catturi l&#8217;essenza di <i>Hugo Iced<\/i> di Hugo Boss? <b>DIVAIN-316<\/b> \u00e8 proprio quello che ti serve. Una composizione aromatico fresca uomini \u2014 pensata per darti quel vibe iconico a una frazione del prezzo.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si apre con <b>menta, t\u00e9<\/b> \u2014 fresco e invitante. Poi si sviluppa in un cuore di <b>arancia amarga, enebro virginia<\/b>, la parte che fa davvero cantare il profumo. E si chiude su una base di <b>vetiver<\/b> per quell&#8217;impressione duratura.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Onestamente, \u00e8 un profumo equilibrato \u2014 ideale in estate, per il giorno. Il tipo di fragranza che diventa la tua firma.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Se ami Hugo Iced ma non vuoi spendere una fortuna per Hugo Boss, <b>DIVAIN-316<\/b> ti d\u00e0 lo stesso carattere senza svuotare il salvadanaio. Un profumo di qualit\u00e0 non dovrebbe essere inaccessibile \u2014 \u00e8 esattamente quello che facciamo qui. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Ricorda Hugo Iced di Hugo Boss<\/p>\n","protected":false},"featured_media":59184,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5182],"product_tag":[4805],"class_list":["post-25684","product","type-product","status-publish","has-post-thumbnail","product_cat-hugo-boss","product_tag-uomo","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product\/25684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/comments?post=25684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media\/59184"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media?parent=25684"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_brand?post=25684"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_cat?post=25684"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_tag?post=25684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}