{"id":25755,"date":"2025-01-31T08:33:08","date_gmt":"2025-01-31T07:33:08","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=25755"},"modified":"2026-07-08T12:13:21","modified_gmt":"2026-07-08T10:13:21","slug":"divain-392","status":"publish","type":"product","link":"https:\/\/divainers.com\/it\/producto\/divain-392\/","title":{"rendered":"divain.392"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Cerchi un profumo che catturi l&#8217;essenza di <i>Explorer<\/i> di Montblanc? <b>DIVAIN-392<\/b> \u00e8 proprio quello che ti serve. Una composizione aromatico legnoso uomini \u2014 pensata per darti quel vibe iconico a una frazione del prezzo.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si apre con <b>bergamotto, pepe rosa, esclarea<\/b> \u2014 fresco e invitante. Poi si sviluppa in un cuore di <b>vetiver hait\u00ed, cuoio<\/b>, la parte che fa davvero cantare il profumo. E si chiude su una base di <b>ambroxan, akigalawood, hojas patchouli indonesia, vaina cacao<\/b> per quell&#8217;impressione duratura.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Onestamente, \u00e8 un profumo equilibrato \u2014 ideale in primavera, per il giorno. Il tipo di fragranza che diventa la tua firma.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Se ami Explorer ma non vuoi spendere una fortuna per Montblanc, <b>DIVAIN-392<\/b> ti d\u00e0 lo stesso carattere senza svuotare il salvadanaio. Un profumo di qualit\u00e0 non dovrebbe essere inaccessibile \u2014 \u00e8 esattamente quello che facciamo qui. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Ricorda Explorer di Montblanc<\/p>\n","protected":false},"featured_media":58575,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5216],"product_tag":[4805],"class_list":["post-25755","product","type-product","status-publish","has-post-thumbnail","product_cat-montblanc","product_tag-uomo","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product\/25755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/comments?post=25755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media\/58575"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media?parent=25755"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_brand?post=25755"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_cat?post=25755"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_tag?post=25755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}