{"id":25800,"date":"2025-01-31T08:32:38","date_gmt":"2025-01-31T07:32:38","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=25800"},"modified":"2026-07-08T11:29:49","modified_gmt":"2026-07-08T09:29:49","slug":"divain-439","status":"publish","type":"product","link":"https:\/\/divainers.com\/it\/producto\/divain-439\/","title":{"rendered":"divain.439"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Cerchi un profumo che catturi l&#8217;essenza di <i>Boss Bottled Elixir<\/i> di Hugo Boss? <b>DIVAIN-439<\/b> \u00e8 proprio quello che ti serve. Una composizione speziato orientale uomini \u2014 pensata per darti quel vibe iconico a una frazione del prezzo.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si apre con <b>incenso, cardamomo<\/b> \u2014 fresco e invitante. Poi si sviluppa in un cuore di <b>vetiver, patchouli<\/b>, la parte che fa davvero cantare il profumo. E si chiude su una base di <b>madera cedro, l\u00e1dano<\/b> per quell&#8217;impressione duratura.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Onestamente, \u00e8 un profumo intenso \u2014 ideale in inverno, per il sera. Il tipo di fragranza che diventa la tua firma.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Se ami Boss Bottled Elixir ma non vuoi spendere una fortuna per Hugo Boss, <b>DIVAIN-439<\/b> ti d\u00e0 lo stesso carattere senza svuotare il salvadanaio. Un profumo di qualit\u00e0 non dovrebbe essere inaccessibile \u2014 \u00e8 esattamente quello che facciamo qui. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Ricorda Boss Bottled Elixir di Hugo Boss<\/p>\n","protected":false},"featured_media":58266,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5182],"product_tag":[4805],"class_list":["post-25800","product","type-product","status-publish","has-post-thumbnail","product_cat-hugo-boss","product_tag-uomo","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product\/25800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/comments?post=25800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media\/58266"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media?parent=25800"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_brand?post=25800"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_cat?post=25800"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_tag?post=25800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}