{"id":26032,"date":"2025-01-31T08:33:05","date_gmt":"2025-01-31T07:33:05","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=26032"},"modified":"2026-07-07T16:06:21","modified_gmt":"2026-07-07T14:06:21","slug":"divain-684","status":"publish","type":"product","link":"https:\/\/divainers.com\/it\/producto\/divain-684\/","title":{"rendered":"divain.684"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Cerchi un profumo che catturi l&#8217;essenza di <i>Intense Caf\u00e9<\/i> di Montale? <b>DIVAIN-684<\/b> \u00e8 proprio quello che ti serve. Una composizione vainilla orientale tutti \u2014 pensata per darti quel vibe iconico a una frazione del prezzo.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si apre con <b>note floreali<\/b> \u2014 fresco e invitante. Poi si sviluppa in un cuore di <b>rosa, caff\u00e8<\/b>, la parte che fa davvero cantare il profumo. E si chiude su una base di <b>vaniglia, muschio blanco, ambra<\/b> per quell&#8217;impressione duratura.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Onestamente, \u00e8 un profumo intenso \u2014 ideale in inverno, per il giorno. Il tipo di fragranza che diventa la tua firma.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Se ami Intense Caf\u00e9 ma non vuoi spendere una fortuna per Montale, <b>DIVAIN-684<\/b> ti d\u00e0 lo stesso carattere senza svuotare il salvadanaio. Un profumo di qualit\u00e0 non dovrebbe essere inaccessibile \u2014 \u00e8 esattamente quello che facciamo qui. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Ricorda Intense Caf\u00e9 di Montale<\/p>\n","protected":false},"featured_media":56430,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5215],"product_tag":[4806],"class_list":["post-26032","product","type-product","status-publish","has-post-thumbnail","product_cat-montale","product_tag-unisex","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product\/26032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/comments?post=26032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media\/56430"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media?parent=26032"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_brand?post=26032"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_cat?post=26032"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_tag?post=26032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}