{"id":26101,"date":"2025-01-31T08:33:14","date_gmt":"2025-01-31T07:33:14","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=26101"},"modified":"2026-07-07T15:00:29","modified_gmt":"2026-07-07T13:00:29","slug":"divain-763","status":"publish","type":"product","link":"https:\/\/divainers.com\/it\/producto\/divain-763\/","title":{"rendered":"divain.763"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Cerchi un profumo che catturi l&#8217;essenza di <i>Bergamask<\/i> di Orto Parisi? <b>DIVAIN-763<\/b> \u00e8 proprio quello che ti serve. Una composizione foug\u00e8re agrumato tutti \u2014 pensata per darti quel vibe iconico a una frazione del prezzo.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si apre con <b>bergamotto, limone<\/b> \u2014 fresco e invitante. Poi si sviluppa in un cuore di <b>fiore d&#8217;arancio, lavanda, mughetto<\/b>, la parte che fa davvero cantare il profumo. E si chiude su una base di <b>cedro, muschio, fava tonka<\/b> per quell&#8217;impressione duratura.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Onestamente, \u00e8 un profumo intenso \u2014 ideale in primavera, per il giorno. Il tipo di fragranza che diventa la tua firma.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Se ami Bergamask ma non vuoi spendere una fortuna per Orto Parisi, <b>DIVAIN-763<\/b> ti d\u00e0 lo stesso carattere senza svuotare il salvadanaio. Un profumo di qualit\u00e0 non dovrebbe essere inaccessibile \u2014 \u00e8 esattamente quello che facciamo qui. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Ricorda Bergamask di Orto Parisi<\/p>\n","protected":false},"featured_media":55839,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5225],"product_tag":[4806],"class_list":["post-26101","product","type-product","status-publish","has-post-thumbnail","product_cat-orto-parisi","product_tag-unisex","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product\/26101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/comments?post=26101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media\/55839"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media?parent=26101"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_brand?post=26101"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_cat?post=26101"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_tag?post=26101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}