{"id":26181,"date":"2025-01-31T08:32:16","date_gmt":"2025-01-31T07:32:16","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=26181"},"modified":"2026-07-07T13:45:49","modified_gmt":"2026-07-07T11:45:49","slug":"divain-848","status":"publish","type":"product","link":"https:\/\/divainers.com\/it\/producto\/divain-848\/","title":{"rendered":"divain.848"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Cerchi un profumo che catturi l&#8217;essenza di <i>Oyedo<\/i> di Diptyque? <b>DIVAIN-848<\/b> \u00e8 proprio quello che ti serve. Una composizione aromatico agrumato tutti \u2014 pensata per darti quel vibe iconico a una frazione del prezzo.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si apre con <b>mandarinam yuzu, limone, lima<\/b> \u2014 fresco e invitante. Poi si sviluppa in un cuore di <b>tomillo<\/b>, la parte che fa davvero cantare il profumo. E si chiude su una base di <b>note legnose<\/b> per quell&#8217;impressione duratura.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Onestamente, \u00e8 un profumo equilibrato \u2014 ideale in estate, per il giorno. Il tipo di fragranza che diventa la tua firma.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Se ami Oyedo ma non vuoi spendere una fortuna per Diptyque, <b>DIVAIN-848<\/b> ti d\u00e0 lo stesso carattere senza svuotare il salvadanaio. Un profumo di qualit\u00e0 non dovrebbe essere inaccessibile \u2014 \u00e8 esattamente quello che facciamo qui. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Ricorda Oyedo di Diptyque<\/p>\n","protected":false},"featured_media":9611,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5163],"product_tag":[4806],"class_list":["post-26181","product","type-product","status-publish","has-post-thumbnail","product_cat-diptyque","product_tag-unisex","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product\/26181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/comments?post=26181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media\/9611"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media?parent=26181"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_brand?post=26181"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_cat?post=26181"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_tag?post=26181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}