{"id":26196,"date":"2025-01-31T08:32:30","date_gmt":"2025-01-31T07:32:30","guid":{"rendered":"https:\/\/divainers.com\/?post_type=product&#038;p=26196"},"modified":"2026-07-07T13:31:38","modified_gmt":"2026-07-07T11:31:38","slug":"divain-865","status":"publish","type":"product","link":"https:\/\/divainers.com\/it\/producto\/divain-865\/","title":{"rendered":"divain.865"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Cerchi un profumo che catturi l&#8217;essenza di <i>Terra di Gioia<\/i> di Giorgio Armani? <b>DIVAIN-865<\/b> \u00e8 proprio quello che ti serve. Una composizione floreale orientale donne \u2014 pensata per darti quel vibe iconico a una frazione del prezzo.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si apre con <b>pera, mandarino, bergamotto<\/b> \u2014 fresco e invitante. Poi si sviluppa in un cuore di <b>flor almendro, gelsomino<\/b>, la parte che fa davvero cantare il profumo. E si chiude su una base di <b>amberwood, muschio<\/b> per quell&#8217;impressione duratura.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Onestamente, \u00e8 un profumo equilibrato \u2014 ideale in estate, per il giorno. Il tipo di fragranza che diventa la tua firma.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Se ami Terra di Gioia ma non vuoi spendere una fortuna per Giorgio Armani, <b>DIVAIN-865<\/b> ti d\u00e0 lo stesso carattere senza svuotare il salvadanaio. Un profumo di qualit\u00e0 non dovrebbe essere inaccessibile \u2014 \u00e8 esattamente quello che facciamo qui. \ud83c\udf39\u2728<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Ricorda Terra di Gioia di Giorgio Armani<\/p>\n","protected":false},"featured_media":55043,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[5273],"product_tag":[4804],"class_list":["post-26196","product","type-product","status-publish","has-post-thumbnail","product_cat-giorgio-armani","product_tag-donna","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product\/26196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/comments?post=26196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media\/55043"}],"wp:attachment":[{"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/media?parent=26196"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_brand?post=26196"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_cat?post=26196"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/divainers.com\/it\/wp-json\/wp\/v2\/product_tag?post=26196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}